{"id":1751,"count":6,"description":"","link":"https:\/\/travelesim.ch\/es\/categoria-esim\/esim-pais-es\/ecuador-es\/","name":"Ecuador","slug":"ecuador-es","taxonomy":"product_cat","parent":195,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>eSIM Ecuador - Travel eSIM<\/title>\n<meta name=\"description\" content=\"eSIM de viaje para Ecuador. Compara planes de datos, compra online y recibe tu eSIM en segundos. Sin gastos de itinerancia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelesim.ch\/es\/categoria-esim\/esim-pais-es\/ecuador-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"eSIM Ecuador - Travel eSIM\" \/>\n<meta property=\"og:description\" content=\"eSIM de viaje para Ecuador. Compara planes de datos, compra online y recibe tu eSIM en segundos. Sin gastos de itinerancia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelesim.ch\/es\/categoria-esim\/esim-pais-es\/ecuador-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Travel eSIM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/travelesim.ch\\\/es\\\/categoria-esim\\\/esim-pais-es\\\/ecuador-es\\\/\",\"url\":\"https:\\\/\\\/travelesim.ch\\\/es\\\/categoria-esim\\\/esim-pais-es\\\/ecuador-es\\\/\",\"name\":\"eSIM Ecuador - Travel eSIM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/travelesim.ch\\\/es\\\/#website\"},\"description\":\"eSIM de viaje para Ecuador. Compara planes de datos, compra online y recibe tu eSIM en segundos. Sin gastos de itinerancia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/travelesim.ch\\\/es\\\/categoria-esim\\\/esim-pais-es\\\/ecuador-es\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/travelesim.ch\\\/es\\\/categoria-esim\\\/esim-pais-es\\\/ecuador-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/travelesim.ch\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"eSIM Pa\u00eds\",\"item\":\"https:\\\/\\\/travelesim.ch\\\/es\\\/categoria-esim\\\/esim-pais-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ecuador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/travelesim.ch\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/travelesim.ch\\\/es\\\/\",\"name\":\"Travel eSIM\",\"description\":\"Itinerancia sin estr\u00e9s\",\"publisher\":{\"@id\":\"https:\\\/\\\/travelesim.ch\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/travelesim.ch\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/travelesim.ch\\\/es\\\/#organization\",\"name\":\"Travel eSIM\",\"url\":\"https:\\\/\\\/travelesim.ch\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/travelesim.ch\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/travelesim.ch\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/etravelsimlogo-tp-bw-big.png\",\"contentUrl\":\"https:\\\/\\\/travelesim.ch\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/etravelsimlogo-tp-bw-big.png\",\"width\":619,\"height\":403,\"caption\":\"Travel eSIM\"},\"image\":{\"@id\":\"https:\\\/\\\/travelesim.ch\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Travelesim\\\/61560670090137\\\/\",\"https:\\\/\\\/www.instagram.com\\\/travelesimch\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/travelesim\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"eSIM Ecuador - Travel eSIM","description":"eSIM de viaje para Ecuador. Compara planes de datos, compra online y recibe tu eSIM en segundos. Sin gastos de itinerancia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelesim.ch\/es\/categoria-esim\/esim-pais-es\/ecuador-es\/","og_locale":"es_ES","og_type":"article","og_title":"eSIM Ecuador - Travel eSIM","og_description":"eSIM de viaje para Ecuador. Compara planes de datos, compra online y recibe tu eSIM en segundos. Sin gastos de itinerancia.","og_url":"https:\/\/travelesim.ch\/es\/categoria-esim\/esim-pais-es\/ecuador-es\/","og_site_name":"Travel eSIM","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/travelesim.ch\/es\/categoria-esim\/esim-pais-es\/ecuador-es\/","url":"https:\/\/travelesim.ch\/es\/categoria-esim\/esim-pais-es\/ecuador-es\/","name":"eSIM Ecuador - Travel eSIM","isPartOf":{"@id":"https:\/\/travelesim.ch\/es\/#website"},"description":"eSIM de viaje para Ecuador. Compara planes de datos, compra online y recibe tu eSIM en segundos. Sin gastos de itinerancia.","breadcrumb":{"@id":"https:\/\/travelesim.ch\/es\/categoria-esim\/esim-pais-es\/ecuador-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/travelesim.ch\/es\/categoria-esim\/esim-pais-es\/ecuador-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/travelesim.ch\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"eSIM Pa\u00eds","item":"https:\/\/travelesim.ch\/es\/categoria-esim\/esim-pais-es\/"},{"@type":"ListItem","position":3,"name":"Ecuador"}]},{"@type":"WebSite","@id":"https:\/\/travelesim.ch\/es\/#website","url":"https:\/\/travelesim.ch\/es\/","name":"Travel eSIM","description":"Itinerancia sin estr\u00e9s","publisher":{"@id":"https:\/\/travelesim.ch\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelesim.ch\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/travelesim.ch\/es\/#organization","name":"Travel eSIM","url":"https:\/\/travelesim.ch\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/travelesim.ch\/es\/#\/schema\/logo\/image\/","url":"https:\/\/travelesim.ch\/wp-content\/uploads\/2024\/05\/etravelsimlogo-tp-bw-big.png","contentUrl":"https:\/\/travelesim.ch\/wp-content\/uploads\/2024\/05\/etravelsimlogo-tp-bw-big.png","width":619,"height":403,"caption":"Travel eSIM"},"image":{"@id":"https:\/\/travelesim.ch\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Travelesim\/61560670090137\/","https:\/\/www.instagram.com\/travelesimch\/","https:\/\/www.linkedin.com\/company\/travelesim\/"]}]}},"_links":{"self":[{"href":"https:\/\/travelesim.ch\/es\/wp-json\/wp\/v2\/product_cat\/1751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelesim.ch\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/travelesim.ch\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/travelesim.ch\/es\/wp-json\/wp\/v2\/product_cat\/195"}],"wp:post_type":[{"href":"https:\/\/travelesim.ch\/es\/wp-json\/wp\/v2\/product?product_cat=1751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}